{"id":20651,"date":"2015-09-21T17:41:01","date_gmt":"2015-09-21T15:41:01","guid":{"rendered":"https:\/\/www.teldat.com\/sin-categorizar\/20651\/internet-de-las-cosas-un-regalo-envenenado\/"},"modified":"2022-12-27T19:07:00","modified_gmt":"2022-12-27T17:07:00","slug":"internet-de-las-cosas-un-regalo-envenenado","status":"publish","type":"post","link":"https:\/\/www.teldat.com\/es\/blog\/internet-de-las-cosas-un-regalo-envenenado\/","title":{"rendered":"Internet de las cosas: \u00bfun regalo envenenado?"},"content":{"rendered":"<p><strong><img decoding=\"async\" class=\"alignleft wp-image-4728\" src=\"https:\/\/www.teldat.com\/wp-content\/uploads\/2022\/06\/177498394-1-scaled.jpg\" alt=\"iot\" width=\"350\" height=\"221\" title=\"\">Este a\u00f1o, el Internet de las cosas (<i>IoT,<\/i> por sus siglas en ingl\u00e9s) conectar\u00e1 a unos 5.000 millones de terminales y dispositivos. \u00bfEs una buena idea desde el punto de vista de la seguridad?\u00a0<\/strong><\/p>\n<p><!--more--><\/p>\n<p>Los dispositivos IP son, a d\u00eda de hoy, algo m\u00e1s que una moda pasajera. Adem\u00e1s, parece que en el futuro la tendencia seguir\u00e1 aumentando: en 2020 se espera que unos <strong>25.000 millones de dispositivos<\/strong> inteligentes est\u00e9n conectados a la red, es decir, un n\u00famero de aparatos que triplica la poblaci\u00f3n actual del planeta.<\/p>\n<p>Para los clientes finales y las empresas, <strong>dispositivos IP <\/strong>como los <em>smartphones<\/em>, las herramientas de control remoto, los coches, los frigor\u00edficos y hasta las pulseras deportivas ofrecen m\u00faltiples ventajas y forman parte de nuestro d\u00eda a d\u00eda. Parece que esto solo acaba de empezar.<\/p>\n<h2><em>Internet of Things: <\/em>luces y sombras<\/h2>\n<p>A pesar de que la propagaci\u00f3n de los dispositivos inteligentes aporta soluciones muy \u00fatiles, el creciente<strong> intercambio de informaci\u00f3n<\/strong> multiplica las<strong> oportunidades de los ciberdelincuentes <\/strong>y les permite acceder a datos sensibles m\u00e1s f\u00e1cilmente.<\/p>\n<p>Por ejemplo, los dispositivos de una empresa que est\u00e9n conectados a su red inform\u00e1tica o a sistemas externos son un blanco perfecto para la manipulaci\u00f3n y el espionaje. De hecho, el uso creciente del <strong>Internet de las cosas <\/strong>puede a abrir lo que antes eran redes independientes para aplicaciones basadas en IP, haci\u00e9ndolas m\u00e1s vulnerables. Es m\u00e1s, las empresas controlan parte de su TI con c\u00e1maras de v\u00eddeo que, a menudo, tambi\u00e9n suelen estar basadas en IP.<\/p>\n<p>La cantidad de piezas y componentes que forman parte de la <strong>infraestructura de redes y aparatos de telecomunicaciones<\/strong> supone, en s\u00ed misma, un desaf\u00edo para la seguridad. La informaci\u00f3n sobre el estado de todos esos <i>routers, switches,<\/i> etc., tiene que ser recopilada y procesada para poder, por ejemplo, distribuir el tr\u00e1fico de red de una forma m\u00e1s eficiente. La <strong>comunicaci\u00f3n IP<\/strong> se vuelve m\u00e1s vulnerable como resultado de la creciente interconexi\u00f3n, y los riesgos asociados a la seguridad se multiplican en las empresas.<\/p>\n<h2>IoT y los problemas de seguridad: \u00bfsoluci\u00f3n a la vista?<\/h2>\n<p>Tanto los usuarios finales como los clientes corporativos deber\u00e1n colaborar para estar lo m\u00e1s seguros posible. No es extra\u00f1o que el <em>firmware<\/em> se actualice tarde (o no se haga nunca). Malos h\u00e1bitos como este puede causar graves problemas en los dispositivos IP, ya que las <em>brechas<\/em><i> en la <\/i><em>seguridad<\/em> pueden no resolverse a tiempo para repeler el siguiente ciberataque.<\/p>\n<p>Resulta evidente que el usuario no es el \u00fanico responsable de asegurarse de que los dispositivos IP est\u00e9n al d\u00eda y, de esta manera, bien protegidos frente a ataques. Los fabricantes tambi\u00e9n deben tratar de dar con la mejor soluci\u00f3n. Por ejemplo, la <em>gateway<\/em> puede proteger a los dispositivos que forman parte de la red.<\/p>\n<p>Como <strong>fabricante de dispositivos empleados en telecomunicaciones, Teldat <\/strong>se compromete a desarrollar y mejorar continuamente sus productos para satisfacer las demandas de sus socios y las de sus clientes.<\/p>\n<p>El impacto que el Internet de las cosas tiene sobre nuestras vidas es evidente y su influencia aumentar\u00e1 en el futuro. Por eso, proporcionar nuevo c\u00f3digo a tiempo resulta crucial para mejorar la seguridad (y lo ser\u00e1 a\u00fan m\u00e1s en los pr\u00f3ximos a\u00f1os).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este a\u00f1o, el Internet de las cosas (IoT, por sus siglas en ingl\u00e9s) conectar\u00e1 a unos 5.000 millones de terminales y dispositivos. \u00bfEs una buena idea desde el punto de vista de la seguridad?\u00a0<\/p>\n","protected":false},"author":240,"featured_media":18347,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1159],"tags":[1123,1373,1752,998,1051,1110],"class_list":["post-20651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-soluciones-seguridad-online-ciberseguridad","tag-iot-es","tag-redes-telecomunicaciones","tag-router-technology","tag-tecnologia-de-routers","tag-telecomunicacion-de-redes"],"acf":[],"wpml_current_locale":"es_ES","wpml_translations":[{"locale":"en_US","id":18629,"slug":"internet-of-things-28iot-29-ip-devices-smart-phone-control-tools","post_title":"The Internet of Things (IoT) \u2013 A blessing and a curse","href":"https:\/\/www.teldat.com\/internet-of-things-28iot-29-ip-devices-smart-phone-control-tools\/"}],"_links":{"self":[{"href":"https:\/\/www.teldat.com\/es\/wp-json\/wp\/v2\/posts\/20651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.teldat.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.teldat.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.teldat.com\/es\/wp-json\/wp\/v2\/users\/240"}],"replies":[{"embeddable":true,"href":"https:\/\/www.teldat.com\/es\/wp-json\/wp\/v2\/comments?post=20651"}],"version-history":[{"count":0,"href":"https:\/\/www.teldat.com\/es\/wp-json\/wp\/v2\/posts\/20651\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.teldat.com\/es\/wp-json\/wp\/v2\/media\/18347"}],"wp:attachment":[{"href":"https:\/\/www.teldat.com\/es\/wp-json\/wp\/v2\/media?parent=20651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.teldat.com\/es\/wp-json\/wp\/v2\/categories?post=20651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.teldat.com\/es\/wp-json\/wp\/v2\/tags?post=20651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}